{"id":5305,"date":"2021-07-04T19:28:00","date_gmt":"2021-07-04T17:28:00","guid":{"rendered":"https:\/\/www.cigars-connect.com\/cigares\/davidoff-winston-churchill-late-hour-churchill\/"},"modified":"2025-07-12T15:35:00","modified_gmt":"2025-07-12T15:35:00","slug":"davidoff-winston-churchill-late-hour-churchill","status":"publish","type":"cigare","link":"https:\/\/www.cigars-connect.com\/en\/cigares\/davidoff-winston-churchill-late-hour-churchill\/","title":{"rendered":"Churchill"},"content":{"rendered":"<p><b>Apparence :<\/b> Cape chocolat tr\u00e8s lisse, soyeuse et bien \u00e9tir\u00e9e. Toucher souple. Remplissage tr\u00e8s homog\u00e8ne.<\/p>\n<p><b>D\u00e9gustation \u00e0 cru :<\/b> Notes v\u00e9g\u00e9tales et bien \u00e9pic\u00e9es. Le tirage est parfait.<\/p>\n<p><b>D\u00c9GUSTATION APR\u00c8S ALLUMAGE :<\/b><\/p>\n<p><b>Premier tiers :<\/b> Attaque simple et efficace. Les ar\u00f4mes, d\u2019abord bois\u00e9s puis rapidement terreux, se mettent en place. Fum\u00e9e ample, odorante et d\u00e9li\u00e9e. Puissance bien calibr\u00e9e. De la rondeur.<\/p>\n<p><b>Deuxi\u00e8me tiers :<\/b> L\u2019\u00e9volution aromatique, tr\u00e8s confortable, est notable. La vitole d\u00e9livre des notes moelleuses de brioche et de c\u00e8dre. Du poivre rouge et des pointes de cuir tann\u00e9 viennent relever le tout.<\/p>\n<p><b>Troisi\u00e8me tiers :<\/b> Beaucoup de pr\u00e9sence et d\u2019expression. Le catalogue aromatique joue avec le moka chaud, quelques pointes de cacao et toujours un bois\u00e9 luxueux. Plein et rassassiant.<\/p>\n<p><b>Conclusion de <i>l&#8217;Amateur<\/i> :<\/b> Une pi\u00e8ce tr\u00e8s soign\u00e9e, presque opulente. Le rythme est remarquable et l\u2019offre gustative de haut niveau. Ensemble tr\u00e8s r\u00e9ussi.<\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"marque":[],"class_list":["post-5305","cigare","type-cigare","status-publish","hentry","no-post-thumbnail"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.3.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Churchill &#8212; Cigars-connect<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cigars-connect.com\/en\/cigares\/davidoff-winston-churchill-late-hour-churchill\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Churchill &#8212; Cigars-connect\" \/>\n<meta property=\"og:description\" content=\"Apparence : Cape chocolat tr\u00e8s lisse, soyeuse et bien \u00e9tir\u00e9e. Toucher souple. Remplissage tr\u00e8s homog\u00e8ne. D\u00e9gustation \u00e0 cru : Notes v\u00e9g\u00e9tales et bien \u00e9pic\u00e9es. Le tirage est parfait. D\u00c9GUSTATION APR\u00c8S ALLUMAGE : Premier tiers : Attaque simple et efficace. Les ar\u00f4mes, d\u2019abord bois\u00e9s puis rapidement terreux, se mettent en place. Fum\u00e9e ample, odorante et d\u00e9li\u00e9e. Puissance bien calibr\u00e9e. De la ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cigars-connect.com\/en\/cigares\/davidoff-winston-churchill-late-hour-churchill\/\" \/>\n<meta property=\"og:site_name\" content=\"Cigars-connect\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/lamateur.decigare\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-12T15:35:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cigars-connect.com\/wp-content\/uploads\/2023\/03\/CRD-davidoff-winston-churchill-late-hour-churchill.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"840\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@cigarsconnect\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.cigars-connect.com\/en\/cigares\/davidoff-winston-churchill-late-hour-churchill\/\",\"url\":\"https:\/\/www.cigars-connect.com\/en\/cigares\/davidoff-winston-churchill-late-hour-churchill\/\",\"name\":\"Churchill &#8212; Cigars-connect\",\"isPartOf\":{\"@id\":\"https:\/\/www.cigars-connect.com\/en\/#website\"},\"datePublished\":\"2021-07-04T17:28:00+00:00\",\"dateModified\":\"2025-07-12T15:35:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.cigars-connect.com\/en\/cigares\/davidoff-winston-churchill-late-hour-churchill\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.cigars-connect.com\/en\/cigares\/davidoff-winston-churchill-late-hour-churchill\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.cigars-connect.com\/en\/cigares\/davidoff-winston-churchill-late-hour-churchill\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.cigars-connect.com\/en\/accueil-2\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cigares\",\"item\":\"https:\/\/www.cigars-connect.com\/en\/cigares\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Churchill\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.cigars-connect.com\/en\/#website\",\"url\":\"https:\/\/www.cigars-connect.com\/en\/\",\"name\":\"Cigars-connect\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.cigars-connect.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.cigars-connect.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.cigars-connect.com\/en\/#organization\",\"name\":\"L'amateur de cigare\",\"url\":\"https:\/\/www.cigars-connect.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.cigars-connect.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.cigars-connect.com\/wp-content\/uploads\/2023\/04\/Logo_ADC_2023.svg\",\"contentUrl\":\"https:\/\/www.cigars-connect.com\/wp-content\/uploads\/2023\/04\/Logo_ADC_2023.svg\",\"width\":1024,\"height\":1024,\"caption\":\"L'amateur de cigare\"},\"image\":{\"@id\":\"https:\/\/www.cigars-connect.com\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/lamateur.decigare\",\"https:\/\/x.com\/cigarsconnect\",\"https:\/\/www.instagram.com\/cigarsconnect\/\",\"https:\/\/www.linkedin.com\/company\/l-amateur-de-cigare\/\",\"https:\/\/www.youtube.com\/@TheIADC\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Churchill &#8212; Cigars-connect","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cigars-connect.com\/en\/cigares\/davidoff-winston-churchill-late-hour-churchill\/","og_locale":"en_US","og_type":"article","og_title":"Churchill &#8212; Cigars-connect","og_description":"Apparence : Cape chocolat tr\u00e8s lisse, soyeuse et bien \u00e9tir\u00e9e. Toucher souple. Remplissage tr\u00e8s homog\u00e8ne. D\u00e9gustation \u00e0 cru : Notes v\u00e9g\u00e9tales et bien \u00e9pic\u00e9es. Le tirage est parfait. D\u00c9GUSTATION APR\u00c8S ALLUMAGE : Premier tiers : Attaque simple et efficace. Les ar\u00f4mes, d\u2019abord bois\u00e9s puis rapidement terreux, se mettent en place. Fum\u00e9e ample, odorante et d\u00e9li\u00e9e. Puissance bien calibr\u00e9e. De la ...","og_url":"https:\/\/www.cigars-connect.com\/en\/cigares\/davidoff-winston-churchill-late-hour-churchill\/","og_site_name":"Cigars-connect","article_publisher":"https:\/\/www.facebook.com\/lamateur.decigare","article_modified_time":"2025-07-12T15:35:00+00:00","og_image":[{"width":600,"height":840,"url":"https:\/\/www.cigars-connect.com\/wp-content\/uploads\/2023\/03\/CRD-davidoff-winston-churchill-late-hour-churchill.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@cigarsconnect","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.cigars-connect.com\/en\/cigares\/davidoff-winston-churchill-late-hour-churchill\/","url":"https:\/\/www.cigars-connect.com\/en\/cigares\/davidoff-winston-churchill-late-hour-churchill\/","name":"Churchill &#8212; Cigars-connect","isPartOf":{"@id":"https:\/\/www.cigars-connect.com\/en\/#website"},"datePublished":"2021-07-04T17:28:00+00:00","dateModified":"2025-07-12T15:35:00+00:00","breadcrumb":{"@id":"https:\/\/www.cigars-connect.com\/en\/cigares\/davidoff-winston-churchill-late-hour-churchill\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cigars-connect.com\/en\/cigares\/davidoff-winston-churchill-late-hour-churchill\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.cigars-connect.com\/en\/cigares\/davidoff-winston-churchill-late-hour-churchill\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.cigars-connect.com\/en\/accueil-2\/"},{"@type":"ListItem","position":2,"name":"Cigares","item":"https:\/\/www.cigars-connect.com\/en\/cigares\/"},{"@type":"ListItem","position":3,"name":"Churchill"}]},{"@type":"WebSite","@id":"https:\/\/www.cigars-connect.com\/en\/#website","url":"https:\/\/www.cigars-connect.com\/en\/","name":"Cigars-connect","description":"","publisher":{"@id":"https:\/\/www.cigars-connect.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cigars-connect.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.cigars-connect.com\/en\/#organization","name":"L'amateur de cigare","url":"https:\/\/www.cigars-connect.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.cigars-connect.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.cigars-connect.com\/wp-content\/uploads\/2023\/04\/Logo_ADC_2023.svg","contentUrl":"https:\/\/www.cigars-connect.com\/wp-content\/uploads\/2023\/04\/Logo_ADC_2023.svg","width":1024,"height":1024,"caption":"L'amateur de cigare"},"image":{"@id":"https:\/\/www.cigars-connect.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/lamateur.decigare","https:\/\/x.com\/cigarsconnect","https:\/\/www.instagram.com\/cigarsconnect\/","https:\/\/www.linkedin.com\/company\/l-amateur-de-cigare\/","https:\/\/www.youtube.com\/@TheIADC"]}]}},"_links":{"self":[{"href":"https:\/\/www.cigars-connect.com\/en\/wp-json\/wp\/v2\/cigare\/5305","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cigars-connect.com\/en\/wp-json\/wp\/v2\/cigare"}],"about":[{"href":"https:\/\/www.cigars-connect.com\/en\/wp-json\/wp\/v2\/types\/cigare"}],"wp:attachment":[{"href":"https:\/\/www.cigars-connect.com\/en\/wp-json\/wp\/v2\/media?parent=5305"}],"wp:term":[{"taxonomy":"marque","embeddable":true,"href":"https:\/\/www.cigars-connect.com\/en\/wp-json\/wp\/v2\/marque?post=5305"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}