{"id":1412,"count":1,"description":"","link":"https:\/\/www.cigars-connect.com\/en\/tag\/plain-packaging\/","name":"Plain packaging","slug":"plain-packaging","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Plain packaging Archives &#8212; Cigars-connect<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cigars-connect.com\/en\/tag\/plain-packaging\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Plain packaging Archives &#8212; Cigars-connect\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cigars-connect.com\/en\/tag\/plain-packaging\/\" \/>\n<meta property=\"og:site_name\" content=\"Cigars-connect\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@cigarsconnect\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.cigars-connect.com\\\/en\\\/tag\\\/plain-packaging\\\/\",\"url\":\"https:\\\/\\\/www.cigars-connect.com\\\/en\\\/tag\\\/plain-packaging\\\/\",\"name\":\"Plain packaging Archives &#8212; Cigars-connect\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cigars-connect.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cigars-connect.com\\\/en\\\/tag\\\/plain-packaging\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cigars-connect.com\\\/en\\\/tag\\\/plain-packaging\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.cigars-connect.com\\\/en\\\/accueil-2\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Plain packaging\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cigars-connect.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.cigars-connect.com\\\/en\\\/\",\"name\":\"Cigars-connect\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cigars-connect.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cigars-connect.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cigars-connect.com\\\/en\\\/#organization\",\"name\":\"L'amateur de cigare\",\"url\":\"https:\\\/\\\/www.cigars-connect.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.cigars-connect.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.cigars-connect.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Logo_ADC_2023.svg\",\"contentUrl\":\"https:\\\/\\\/www.cigars-connect.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Logo_ADC_2023.svg\",\"width\":1024,\"height\":1024,\"caption\":\"L'amateur de cigare\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cigars-connect.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/lamateur.decigare\",\"https:\\\/\\\/x.com\\\/cigarsconnect\",\"https:\\\/\\\/www.instagram.com\\\/cigarsconnect\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/l-amateur-de-cigare\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@TheIADC\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Plain packaging Archives &#8212; Cigars-connect","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cigars-connect.com\/en\/tag\/plain-packaging\/","og_locale":"en_US","og_type":"article","og_title":"Plain packaging Archives &#8212; Cigars-connect","og_url":"https:\/\/www.cigars-connect.com\/en\/tag\/plain-packaging\/","og_site_name":"Cigars-connect","twitter_card":"summary_large_image","twitter_site":"@cigarsconnect","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.cigars-connect.com\/en\/tag\/plain-packaging\/","url":"https:\/\/www.cigars-connect.com\/en\/tag\/plain-packaging\/","name":"Plain packaging Archives &#8212; Cigars-connect","isPartOf":{"@id":"https:\/\/www.cigars-connect.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/www.cigars-connect.com\/en\/tag\/plain-packaging\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.cigars-connect.com\/en\/tag\/plain-packaging\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.cigars-connect.com\/en\/accueil-2\/"},{"@type":"ListItem","position":2,"name":"Plain packaging"}]},{"@type":"WebSite","@id":"https:\/\/www.cigars-connect.com\/en\/#website","url":"https:\/\/www.cigars-connect.com\/en\/","name":"Cigars-connect","description":"","publisher":{"@id":"https:\/\/www.cigars-connect.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cigars-connect.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.cigars-connect.com\/en\/#organization","name":"L'amateur de cigare","url":"https:\/\/www.cigars-connect.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.cigars-connect.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.cigars-connect.com\/wp-content\/uploads\/2023\/04\/Logo_ADC_2023.svg","contentUrl":"https:\/\/www.cigars-connect.com\/wp-content\/uploads\/2023\/04\/Logo_ADC_2023.svg","width":1024,"height":1024,"caption":"L'amateur de cigare"},"image":{"@id":"https:\/\/www.cigars-connect.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/lamateur.decigare","https:\/\/x.com\/cigarsconnect","https:\/\/www.instagram.com\/cigarsconnect\/","https:\/\/www.linkedin.com\/company\/l-amateur-de-cigare\/","https:\/\/www.youtube.com\/@TheIADC"]}]}},"_links":{"self":[{"href":"https:\/\/www.cigars-connect.com\/en\/wp-json\/wp\/v2\/tags\/1412","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cigars-connect.com\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.cigars-connect.com\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.cigars-connect.com\/en\/wp-json\/wp\/v2\/posts?tags=1412"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}